{"id":19877,"date":"2020-03-12T09:31:00","date_gmt":"2020-03-12T02:31:00","guid":{"rendered":"http:\/\/www.en.kku.ac.th\/web\/?p=19877"},"modified":"2020-03-12T09:31:00","modified_gmt":"2020-03-12T02:31:00","slug":"%e0%b8%84%e0%b8%93%e0%b8%9a%e0%b8%94%e0%b8%b5%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a7%e0%b8%b4%e0%b8%a8%e0%b8%a7%e0%b8%af-%e0%b8%a3%e0%b9%88%e0%b8%a7%e0%b8%a1%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8","status":"publish","type":"post","link":"https:\/\/www.en.kku.ac.th\/web\/%e0%b8%84%e0%b8%93%e0%b8%9a%e0%b8%94%e0%b8%b5%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a7%e0%b8%b4%e0%b8%a8%e0%b8%a7%e0%b8%af-%e0%b8%a3%e0%b9%88%e0%b8%a7%e0%b8%a1%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8\/","title":{"rendered":"\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e20\u0e32\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 42"},"content":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 11 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2563 \u0e23\u0e28.\u0e14\u0e23.\u0e23\u0e31\u0e0a\u0e1e\u0e25 \u0e2a\u0e31\u0e19\u0e15\u0e34\u0e27\u0e23\u0e32\u0e01\u0e23 \u00a0\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e20\u0e32\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 42 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3 (1\/2563) \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e0a\u0e31\u0e49\u0e19 3 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e23\u0e32\u0e0a\u0e21\u0e07\u0e04\u0e25\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u00a0\u0e01\u0e32\u0e23\u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01 Accreditation Board for Engineering and Technology (ABET) \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e35 \u0e1e.\u0e28.2565 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 11 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2563 \u0e23\u0e28.\u0e14\u0e23.\u0e23\u0e31\u0e0a\u0e1e\u0e25 \u0e2a\u0e31\u0e19\u0e15\u0e34\u0e27\u0e23\u0e32\u0e01\u0e23 \u00a0\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e20\u0e32\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 42 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3 (1\/2563) \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e0a\u0e31\u0e49\u0e19 3 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e23\u0e32\u0e0a\u0e21\u0e07\u0e04\u0e25\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u00a0\u0e01\u0e32\u0e23\u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01 Accreditation Board for Engineering and Technology (ABET) \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e35 \u0e1e.\u0e28.2565 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19<\/p>\n","protected":false},"author":8,"featured_media":19878,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1"],"rttpg_featured_image_url":{"full":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",1548,1161,false],"landscape":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",1548,1161,false],"portraits":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",1548,1161,false],"thumbnail":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",128,96,false],"medium":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",1548,1161,false],"large":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",1548,1161,false],"1536x1536":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n-1536x1152.jpg",1536,1152,true],"2048x2048":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",1548,1161,false],"tp-image-grid":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",700,525,false],"unipix-blog":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",560,420,false],"unipix-blog-2":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",160,120,false],"unipix-blog-3":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",280,210,false],"unipix-professor":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",300,225,false],"unipix-portfolio":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",347,260,false],"unipix-portfolio-2":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",387,290,false],"unipix-program":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",300,225,false],"unipix-research":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",410,308,false],"unipix-footer-blog":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2020\/03\/89635358_1142799942739551_248610836149436416_n.jpg",80,60,false]},"rttpg_author":{"display_name":"\u0e1d\u0e48\u0e32\u0e22\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23","author_link":"https:\/\/www.en.kku.ac.th\/web\/author\/webenpr\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.en.kku.ac.th\/web\/category\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%93%e0%b8%b0\/\" rel=\"category tag\">\u0e02\u0e48\u0e32\u0e27\u0e04\u0e13\u0e30<\/a>","rttpg_excerpt":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 11 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2563 \u0e23\u0e28.\u0e14\u0e23.\u0e23\u0e31\u0e0a\u0e1e\u0e25 \u0e2a\u0e31\u0e19\u0e15\u0e34\u0e27\u0e23\u0e32\u0e01\u0e23 \u00a0\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e20\u0e32\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 42 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3 (1\/2563) \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e0a\u0e31\u0e49\u0e19 3 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e23\u0e32\u0e0a\u0e21\u0e07\u0e04\u0e25\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u00a0\u0e01\u0e32\u0e23\u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01 Accreditation Board for Engineering and Technology (ABET) \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e35 \u0e1e.\u0e28.2565 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19","_links":{"self":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/19877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/comments?post=19877"}],"version-history":[{"count":2,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/19877\/revisions"}],"predecessor-version":[{"id":19880,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/19877\/revisions\/19880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/media\/19878"}],"wp:attachment":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/media?parent=19877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/categories?post=19877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/tags?post=19877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}