{"id":22679,"date":"2021-01-04T10:50:39","date_gmt":"2021-01-04T03:50:39","guid":{"rendered":"http:\/\/www.en.kku.ac.th\/web\/?p=22679"},"modified":"2021-01-04T10:53:13","modified_gmt":"2021-01-04T03:53:13","slug":"%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a7%e0%b8%b4%e0%b8%a8%e0%b8%a7%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-%e0%b9%84%e0%b8%94%e0%b9%89%e0%b9%83%e0%b8%ab","status":"publish","type":"post","link":"https:\/\/www.en.kku.ac.th\/web\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a7%e0%b8%b4%e0%b8%a8%e0%b8%a7%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-%e0%b9%84%e0%b8%94%e0%b9%89%e0%b9%83%e0%b8%ab\/","title":{"rendered":"\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e1a\u0e01 \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 \u201c\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e22\u0e34\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e34\u0e07\u0e25\u0e39\u0e01\u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e02\u0e19\u0e32\u0e14 120 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e40\u0e21\u0e15\u0e23\u201d"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 23 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563\u00a0\u00a0 \u0e23\u0e28.\u0e14\u0e23.\u0e23\u0e31\u0e0a\u0e1e\u0e25 \u0e2a\u0e31\u0e19\u0e15\u0e34\u0e27\u0e23\u0e32\u0e01\u0e23 \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e28.\u0e14\u0e23.\u0e08\u0e35\u0e23\u0e19\u0e38\u0e0a \u0e40\u0e2a\u0e07\u0e35\u0e48\u0e22\u0e21\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e27\u0e34\u0e40\u0e17\u0e28\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u00a0 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\u00a0 \u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u00a0\u00a0 \u0e1e\u0e25\u0e40\u0e2d\u0e01\u0e23\u0e13\u0e20\u0e1e \u0e08\u0e31\u0e19\u0e17\u0e23\u0e19\u0e34\u0e22\u0e21\u00a0 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e17\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e1a\u0e01 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30 \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e02\u0e49\u0e32\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e38\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e22\u0e38\u0e17\u0e42\u0e18\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u00a0\u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e22\u0e34\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e34\u0e07\u0e25\u0e39\u0e01\u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e02\u0e19\u0e32\u0e14 120 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e40\u0e21\u0e15\u0e23\u201d \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35 \u0e23\u0e28.\u0e14\u0e23.\u0e1e\u0e07\u0e28\u0e01\u0e23 \u0e1e\u0e23\u0e23\u0e13\u0e23\u0e31\u0e15\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c[\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;22681,22682,22683,22684,22685,22686,22687,22688,22689,22690,22691&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 23 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563\u00a0\u00a0 \u0e23\u0e28.\u0e14\u0e23.\u0e23\u0e31\u0e0a\u0e1e\u0e25 \u0e2a\u0e31\u0e19\u0e15\u0e34\u0e27\u0e23\u0e32\u0e01\u0e23 \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e28.\u0e14\u0e23.\u0e08\u0e35\u0e23\u0e19\u0e38\u0e0a \u0e40\u0e2a\u0e07\u0e35\u0e48\u0e22\u0e21\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e27\u0e34\u0e40\u0e17\u0e28\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u00a0 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\u00a0 \u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u00a0\u00a0 \u0e1e\u0e25\u0e40\u0e2d\u0e01\u0e23\u0e13\u0e20\u0e1e \u0e08\u0e31\u0e19\u0e17\u0e23\u0e19\u0e34\u0e22\u0e21\u00a0 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e17\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e1a\u0e01 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30 \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e02\u0e49\u0e32\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e38\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e22\u0e38\u0e17\u0e42\u0e18\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u00a0\u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e22\u0e34\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e34\u0e07\u0e25\u0e39\u0e01\u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e02\u0e19\u0e32\u0e14 120 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e40\u0e21\u0e15\u0e23\u201d \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35 \u0e23\u0e28.\u0e14\u0e23.\u0e1e\u0e07\u0e28\u0e01\u0e23 \u0e1e\u0e23\u0e23\u0e13\u0e23\u0e31\u0e15\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c[\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;22681,22682,22683,22684,22685,22686,22687,22688,22689,22690,22691&#8243;][\/vc_column]&#8230;<\/p>\n","protected":false},"author":8,"featured_media":22690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-22679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1"],"rttpg_featured_image_url":{"full":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",1920,1280,false],"landscape":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",1920,1280,false],"portraits":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",1920,1280,false],"thumbnail":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",128,85,false],"medium":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",1920,1280,false],"large":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",1920,1280,false],"1536x1536":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",1920,1280,false],"tp-image-grid":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",700,467,false],"unipix-blog":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",615,410,false],"unipix-blog-2":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",180,120,false],"unipix-blog-3":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",280,187,false],"unipix-professor":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",300,200,false],"unipix-portfolio":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",360,240,false],"unipix-portfolio-2":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",400,267,false],"unipix-program":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",300,200,false],"unipix-research":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",410,273,false],"unipix-footer-blog":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/01\/DSC_6898.jpg",80,53,false]},"rttpg_author":{"display_name":"\u0e1d\u0e48\u0e32\u0e22\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23","author_link":"https:\/\/www.en.kku.ac.th\/web\/author\/webenpr\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.en.kku.ac.th\/web\/category\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%93%e0%b8%b0\/\" rel=\"category tag\">\u0e02\u0e48\u0e32\u0e27\u0e04\u0e13\u0e30<\/a>","rttpg_excerpt":"[vc_row][vc_column][vc_column_text]\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 23 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563\u00a0\u00a0 \u0e23\u0e28.\u0e14\u0e23.\u0e23\u0e31\u0e0a\u0e1e\u0e25 \u0e2a\u0e31\u0e19\u0e15\u0e34\u0e27\u0e23\u0e32\u0e01\u0e23 \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e28.\u0e14\u0e23.\u0e08\u0e35\u0e23\u0e19\u0e38\u0e0a \u0e40\u0e2a\u0e07\u0e35\u0e48\u0e22\u0e21\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e27\u0e34\u0e40\u0e17\u0e28\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u00a0 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\u00a0 \u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u00a0\u00a0 \u0e1e\u0e25\u0e40\u0e2d\u0e01\u0e23\u0e13\u0e20\u0e1e \u0e08\u0e31\u0e19\u0e17\u0e23\u0e19\u0e34\u0e22\u0e21\u00a0 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e17\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e1a\u0e01 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30 \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e02\u0e49\u0e32\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e38\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e22\u0e38\u0e17\u0e42\u0e18\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u00a0\u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e22\u0e34\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e34\u0e07\u0e25\u0e39\u0e01\u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e02\u0e19\u0e32\u0e14 120 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e40\u0e21\u0e15\u0e23\u201d \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35 \u0e23\u0e28.\u0e14\u0e23.\u0e1e\u0e07\u0e28\u0e01\u0e23 \u0e1e\u0e23\u0e23\u0e13\u0e23\u0e31\u0e15\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c[\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;22681,22682,22683,22684,22685,22686,22687,22688,22689,22690,22691&#8243;][\/vc_column]...","_links":{"self":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/22679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/comments?post=22679"}],"version-history":[{"count":2,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/22679\/revisions"}],"predecessor-version":[{"id":22692,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/22679\/revisions\/22692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/media\/22690"}],"wp:attachment":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/media?parent=22679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/categories?post=22679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/tags?post=22679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}