{"id":23978,"date":"2021-09-07T11:54:38","date_gmt":"2021-09-07T04:54:38","guid":{"rendered":"http:\/\/www.en.kku.ac.th\/web\/?p=23978"},"modified":"2021-09-07T11:54:38","modified_gmt":"2021-09-07T04:54:38","slug":"%e0%b8%84%e0%b8%93%e0%b8%9a%e0%b8%94%e0%b8%b5-%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%a3%e0%b8%b2%e0%b8%87%e0%b8%a7%e0%b8%b1%e0%b8%a5%e0%b9%80%e0%b8%8a%e0%b8%b4%e0%b8%94%e0%b8%8a%e0%b8%b9%e0%b9%80%e0%b8%81","status":"publish","type":"post","link":"https:\/\/www.en.kku.ac.th\/web\/%e0%b8%84%e0%b8%93%e0%b8%9a%e0%b8%94%e0%b8%b5-%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%a3%e0%b8%b2%e0%b8%87%e0%b8%a7%e0%b8%b1%e0%b8%a5%e0%b9%80%e0%b8%8a%e0%b8%b4%e0%b8%94%e0%b8%8a%e0%b8%b9%e0%b9%80%e0%b8%81\/","title":{"rendered":"\u0e04\u0e13\u0e1a\u0e14\u0e35 \u0e21\u0e2d\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2564"},"content":{"rendered":"<p>\u0e23\u0e28.\u0e14\u0e23.\u0e23\u0e31\u0e0a\u0e1e\u0e25 \u0e2a\u0e31\u0e19\u0e15\u0e34\u0e27\u0e23\u0e32\u0e01\u0e23 \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e1c\u0e28.\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e15\u0e34\u0e1e\u0e07\u0e29\u0e4c \u0e25\u0e32\u0e25\u0e38\u0e19 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e21\u0e2d\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e21\u0e2d\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2564 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e21\u0e2d\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07 \u00a0\u00a0\u00a0\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u00a0\u00a0\u00a0 \u00a0\u0e04\u0e37\u0e2d\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2d\u0e34\u0e19\u0e17\u0e34\u0e23\u0e32\u00a0 \u0e2b\u0e27\u0e48\u0e32\u0e19\u0e02\u0e35\u0e49\u0e40\u0e2b\u0e25\u0e47\u0e01\u00a0\u00a0 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3 \u00a0\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e21\u0e35 \u00a0\u0e14\u0e49\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e44\u0e17\u0e22\u00a0\u00a0 \u00a0\u0e04\u0e37\u0e2d\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e16\u0e34\u0e23\u0e29\u0e34\u0e21\u0e32\u00a0 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e0a\u0e49\u0e32\u0e07\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3\u00a0 \u00a0\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e21\u0e35 \u00a0\u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e08\u0e34\u0e15\u0e2d\u0e32\u0e2a\u0e32\u00a0\u00a0 \u00a0\u0e04\u0e37\u0e2d\u00a0 \u00a0 \u00a0\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e02\u0e19\u0e34\u0e29\u0e10\u0e32\u00a0 \u0e1a\u0e38\u0e0d\u0e2a\u0e21\u0e31\u0e04\u0e23\u00a0\u00a0\u00a0\u00a0 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 2\u00a0\u00a0 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25<br \/>\n\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e02\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e23\u0e22\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e2d\u0e14\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e14\u0e49\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e04\u0e27\u0e32\u0e21\u0e21\u0e35\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e15\u0e48\u0e2d\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21<br \/>\n<img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-23980\" src=\"https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241068746_882831679327409_7601671989330354122_n.jpg\" alt=\"\" width=\"2024\" height=\"1344\" srcset=\"https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241068746_882831679327409_7601671989330354122_n.jpg 2024w, https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241068746_882831679327409_7601671989330354122_n-1536x1020.jpg 1536w, https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241068746_882831679327409_7601671989330354122_n-272x182.jpg 272w\" sizes=\"(max-width: 2024px) 100vw, 2024px\" \/><img decoding=\"async\" class=\"alignnone size-medium wp-image-23981\" src=\"https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241073366_367688474853164_2295359179221435607_n.jpg\" alt=\"\" width=\"2024\" height=\"1300\" srcset=\"https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241073366_367688474853164_2295359179221435607_n.jpg 2024w, https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241073366_367688474853164_2295359179221435607_n-1536x987.jpg 1536w\" sizes=\"(max-width: 2024px) 100vw, 2024px\" \/><img decoding=\"async\" class=\"alignnone size-medium wp-image-23982\" src=\"https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241098400_3035314486746025_7058567642772703343_n.jpg\" alt=\"\" width=\"2024\" height=\"1186\" srcset=\"https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241098400_3035314486746025_7058567642772703343_n.jpg 2024w, https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241098400_3035314486746025_7058567642772703343_n-1536x900.jpg 1536w\" sizes=\"(max-width: 2024px) 100vw, 2024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e23\u0e28.\u0e14\u0e23.\u0e23\u0e31\u0e0a\u0e1e\u0e25 \u0e2a\u0e31\u0e19\u0e15\u0e34\u0e27\u0e23\u0e32\u0e01\u0e23 \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e1c\u0e28.\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e15\u0e34\u0e1e\u0e07\u0e29\u0e4c \u0e25\u0e32\u0e25\u0e38\u0e19 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e21\u0e2d\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e21\u0e2d\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2564 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e21\u0e2d\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07 \u00a0\u00a0\u00a0\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u00a0\u00a0\u00a0 \u00a0\u0e04\u0e37\u0e2d\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2d\u0e34\u0e19\u0e17\u0e34\u0e23\u0e32\u00a0 \u0e2b\u0e27\u0e48\u0e32\u0e19\u0e02\u0e35\u0e49\u0e40\u0e2b\u0e25\u0e47\u0e01\u00a0\u00a0 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3 \u00a0\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e21\u0e35 \u00a0\u0e14\u0e49\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e44\u0e17\u0e22\u00a0\u00a0 \u00a0\u0e04\u0e37\u0e2d\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e16\u0e34\u0e23\u0e29\u0e34\u0e21\u0e32\u00a0 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e0a\u0e49\u0e32\u0e07\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3\u00a0 \u00a0\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e21\u0e35 \u00a0\u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e08\u0e34\u0e15\u0e2d\u0e32\u0e2a\u0e32\u00a0\u00a0 \u00a0\u0e04\u0e37\u0e2d\u00a0 \u00a0 \u00a0\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e02\u0e19\u0e34\u0e29\u0e10\u0e32\u00a0 \u0e1a\u0e38\u0e0d\u0e2a\u0e21\u0e31\u0e04\u0e23\u00a0\u00a0\u00a0\u00a0 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 2\u00a0\u00a0 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e02\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e23\u0e22\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e2d\u0e14\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e14\u0e49\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e04\u0e27\u0e32\u0e21\u0e21\u0e35\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e15\u0e48\u0e2d\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21<\/p>\n","protected":false},"author":8,"featured_media":23979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-23978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1"],"rttpg_featured_image_url":{"full":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",2024,1349,false],"landscape":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",2024,1349,false],"portraits":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",2024,1349,false],"thumbnail":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",128,85,false],"medium":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",2024,1349,false],"large":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",2024,1349,false],"1536x1536":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",2024,1349,false],"tp-image-grid":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",700,467,false],"unipix-blog":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",615,410,false],"unipix-blog-2":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",180,120,false],"unipix-blog-3":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",280,187,false],"unipix-professor":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",300,200,false],"unipix-portfolio":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",360,240,false],"unipix-portfolio-2":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",400,267,false],"unipix-program":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",300,200,false],"unipix-research":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",410,273,false],"unipix-footer-blog":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2021\/09\/241069309_204952991617274_6489387589722324762_n.jpg",80,53,false]},"rttpg_author":{"display_name":"\u0e1d\u0e48\u0e32\u0e22\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23","author_link":"https:\/\/www.en.kku.ac.th\/web\/author\/webenpr\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.en.kku.ac.th\/web\/category\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%93%e0%b8%b0\/\" rel=\"category tag\">\u0e02\u0e48\u0e32\u0e27\u0e04\u0e13\u0e30<\/a>","rttpg_excerpt":"\u0e23\u0e28.\u0e14\u0e23.\u0e23\u0e31\u0e0a\u0e1e\u0e25 \u0e2a\u0e31\u0e19\u0e15\u0e34\u0e27\u0e23\u0e32\u0e01\u0e23 \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e1c\u0e28.\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e15\u0e34\u0e1e\u0e07\u0e29\u0e4c \u0e25\u0e32\u0e25\u0e38\u0e19 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e21\u0e2d\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e21\u0e2d\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2564 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e21\u0e2d\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07 \u00a0\u00a0\u00a0\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u00a0\u00a0\u00a0 \u00a0\u0e04\u0e37\u0e2d\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2d\u0e34\u0e19\u0e17\u0e34\u0e23\u0e32\u00a0 \u0e2b\u0e27\u0e48\u0e32\u0e19\u0e02\u0e35\u0e49\u0e40\u0e2b\u0e25\u0e47\u0e01\u00a0\u00a0 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3 \u00a0\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e21\u0e35 \u00a0\u0e14\u0e49\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e44\u0e17\u0e22\u00a0\u00a0 \u00a0\u0e04\u0e37\u0e2d\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e16\u0e34\u0e23\u0e29\u0e34\u0e21\u0e32\u00a0 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e0a\u0e49\u0e32\u0e07\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3\u00a0 \u00a0\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e21\u0e35 \u00a0\u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e08\u0e34\u0e15\u0e2d\u0e32\u0e2a\u0e32\u00a0\u00a0 \u00a0\u0e04\u0e37\u0e2d\u00a0 \u00a0 \u00a0\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e02\u0e19\u0e34\u0e29\u0e10\u0e32\u00a0 \u0e1a\u0e38\u0e0d\u0e2a\u0e21\u0e31\u0e04\u0e23\u00a0\u00a0\u00a0\u00a0 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 2\u00a0\u00a0 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e02\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e23\u0e22\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e2d\u0e14\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e14\u0e49\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e04\u0e27\u0e32\u0e21\u0e21\u0e35\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e15\u0e48\u0e2d\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21","_links":{"self":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/23978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/comments?post=23978"}],"version-history":[{"count":1,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/23978\/revisions"}],"predecessor-version":[{"id":23983,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/23978\/revisions\/23983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/media\/23979"}],"wp:attachment":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/media?parent=23978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/categories?post=23978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/tags?post=23978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}