{"id":25990,"date":"2022-05-19T10:15:16","date_gmt":"2022-05-19T03:15:16","guid":{"rendered":"http:\/\/www.en.kku.ac.th\/web\/?p=25990"},"modified":"2022-05-19T10:15:16","modified_gmt":"2022-05-19T03:15:16","slug":"%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a7%e0%b8%b4%e0%b8%a8%e0%b8%a7%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-%e0%b8%82%e0%b8%ad%e0%b9%81%e0%b8%aa%e0%b8%94","status":"publish","type":"post","link":"https:\/\/www.en.kku.ac.th\/web\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a7%e0%b8%b4%e0%b8%a8%e0%b8%a7%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-%e0%b8%82%e0%b8%ad%e0%b9%81%e0%b8%aa%e0%b8%94\/","title":{"rendered":"\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c  \u0e02\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32 \u0e1b.\u0e40\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e22\u0e28 \u0e28.\u0e14\u0e23.\u0e01\u0e19\u0e01 \u0e27\u0e07\u0e29\u0e4c\u0e15\u0e23\u0e30\u0e2b\u0e07\u0e48\u0e32\u0e19 \u0e40\u0e19\u0e49\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19 \u0e22\u0e01\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e0a\u0e32\u0e27\u0e2d\u0e35\u0e2a\u0e32\u0e19"},"content":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 17 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2565\u00a0 \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u201c\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e2a\u0e27\u0e21\u0e2b\u0e21\u0e27\u0e01\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u201d \u0e42\u0e14\u0e22 <strong>\u0e14\u0e23.\u0e40\u0e08\u0e29\u0e0e\u0e32 \u0e04\u0e33\u0e1c\u0e2d\u0e07<\/strong> \u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32\u00a0 \u00a0\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35<em><strong>\u00a0\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e18\u0e40\u0e19\u0e28 \u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e19\u0e32\u0e21<\/strong><\/em>\u00a0\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u201d \u00a0\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a<em><strong>\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e22\u0e28 \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e01\u0e19\u0e01 \u0e27\u0e07\u0e29\u0e4c\u0e15\u0e23\u0e30\u0e2b\u0e07\u0e48\u0e32\u0e19<\/strong><\/em><em>\u00a0<\/em><strong><em>\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 <\/em><\/strong><strong><em>10<\/em><\/strong> \u0e08\u0e31\u0e14\u0e42\u0e14\u0e22 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\u00a0 \u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e22\u0e28 \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e01\u0e19\u0e01 \u00a0\u0e27\u0e07\u0e29\u0e4c\u0e15\u0e23\u0e30\u0e2b\u0e07\u0e48\u0e32\u0e19 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 10 \u0e41\u0e25\u0e30\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 11 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2563-2564 \u0e13\u00a0 \u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e34\u0e23\u0e34\u0e04\u0e38\u0e13\u0e32\u0e01\u0e23 4 \u0e0a\u0e31\u0e49\u0e19 2 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e34\u0e23\u0e34\u0e04\u0e38\u0e13\u0e32\u0e01\u0e23 \u00a0\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u00a0\u0e42\u0e14\u0e22\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e17\u0e33\u0e04\u0e38\u0e13\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 17 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2565\u00a0 \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u201c\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e2a\u0e27\u0e21\u0e2b\u0e21\u0e27\u0e01\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u201d \u0e42\u0e14\u0e22 \u0e14\u0e23.\u0e40\u0e08\u0e29\u0e0e\u0e32 \u0e04\u0e33\u0e1c\u0e2d\u0e07 \u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32\u00a0 \u00a0\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u00a0\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e18\u0e40\u0e19\u0e28 \u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e19\u0e32\u0e21\u00a0\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u201d \u00a0\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e22\u0e28 \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e01\u0e19\u0e01 \u0e27\u0e07\u0e29\u0e4c\u0e15\u0e23\u0e30\u0e2b\u0e07\u0e48\u0e32\u0e19\u00a0\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 10 \u0e08\u0e31\u0e14\u0e42\u0e14\u0e22 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\u00a0 \u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e22\u0e28 \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e01\u0e19\u0e01 \u00a0\u0e27\u0e07\u0e29\u0e4c\u0e15\u0e23\u0e30\u0e2b\u0e07\u0e48\u0e32\u0e19 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 10 \u0e41\u0e25\u0e30\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 11 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2563-2564 \u0e13\u00a0 \u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e34\u0e23\u0e34\u0e04\u0e38\u0e13\u0e32\u0e01\u0e23 4 \u0e0a\u0e31\u0e49\u0e19 2 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e34\u0e23\u0e34\u0e04\u0e38\u0e13\u0e32\u0e01\u0e23 \u00a0\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u00a0\u0e42\u0e14\u0e22\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e17\u0e33\u0e04\u0e38\u0e13\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21<\/p>\n","protected":false},"author":8,"featured_media":25991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1"],"rttpg_featured_image_url":{"full":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",1331,741,false],"landscape":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",1331,741,false],"portraits":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",1331,741,false],"thumbnail":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",128,71,false],"medium":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",1331,741,false],"large":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",1331,741,false],"1536x1536":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",1331,741,false],"2048x2048":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",1331,741,false],"tp-image-grid":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",700,390,false],"unipix-blog":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",615,342,false],"unipix-blog-2":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",190,106,false],"unipix-blog-3":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",280,156,false],"unipix-professor":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",300,167,false],"unipix-portfolio":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",360,200,false],"unipix-portfolio-2":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",400,223,false],"unipix-program":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",300,167,false],"unipix-research":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",410,228,false],"unipix-footer-blog":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/05\/01-1.jpg",80,45,false]},"rttpg_author":{"display_name":"\u0e1d\u0e48\u0e32\u0e22\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23","author_link":"https:\/\/www.en.kku.ac.th\/web\/author\/webenpr\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.en.kku.ac.th\/web\/category\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%93%e0%b8%b0\/\" rel=\"category tag\">\u0e02\u0e48\u0e32\u0e27\u0e04\u0e13\u0e30<\/a>","rttpg_excerpt":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 17 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2565\u00a0 \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u201c\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e2a\u0e27\u0e21\u0e2b\u0e21\u0e27\u0e01\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u201d \u0e42\u0e14\u0e22 \u0e14\u0e23.\u0e40\u0e08\u0e29\u0e0e\u0e32 \u0e04\u0e33\u0e1c\u0e2d\u0e07 \u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32\u00a0 \u00a0\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u00a0\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e18\u0e40\u0e19\u0e28 \u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e19\u0e32\u0e21\u00a0\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u201d \u00a0\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e22\u0e28 \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e01\u0e19\u0e01 \u0e27\u0e07\u0e29\u0e4c\u0e15\u0e23\u0e30\u0e2b\u0e07\u0e48\u0e32\u0e19\u00a0\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 10 \u0e08\u0e31\u0e14\u0e42\u0e14\u0e22 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\u00a0 \u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e22\u0e28 \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e01\u0e19\u0e01 \u00a0\u0e27\u0e07\u0e29\u0e4c\u0e15\u0e23\u0e30\u0e2b\u0e07\u0e48\u0e32\u0e19 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 10 \u0e41\u0e25\u0e30\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 11 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2563-2564 \u0e13\u00a0 \u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e34\u0e23\u0e34\u0e04\u0e38\u0e13\u0e32\u0e01\u0e23 4 \u0e0a\u0e31\u0e49\u0e19 2 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e34\u0e23\u0e34\u0e04\u0e38\u0e13\u0e32\u0e01\u0e23 \u00a0\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u00a0\u0e42\u0e14\u0e22\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e17\u0e33\u0e04\u0e38\u0e13\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21","_links":{"self":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/25990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/comments?post=25990"}],"version-history":[{"count":1,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/25990\/revisions"}],"predecessor-version":[{"id":25992,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/25990\/revisions\/25992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/media\/25991"}],"wp:attachment":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/media?parent=25990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/categories?post=25990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/tags?post=25990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}