{"id":27069,"date":"2022-09-09T17:05:47","date_gmt":"2022-09-09T10:05:47","guid":{"rendered":"https:\/\/www.en.kku.ac.th\/web\/?p=27069"},"modified":"2022-09-09T17:05:47","modified_gmt":"2022-09-09T10:05:47","slug":"%e0%b8%9a%e0%b8%b8%e0%b8%84%e0%b8%a5%e0%b8%b2%e0%b8%81%e0%b8%a3%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a7%e0%b8%b4%e0%b8%a8%e0%b8%a7%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95","status":"publish","type":"post","link":"https:\/\/www.en.kku.ac.th\/web\/%e0%b8%9a%e0%b8%b8%e0%b8%84%e0%b8%a5%e0%b8%b2%e0%b8%81%e0%b8%a3%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a7%e0%b8%b4%e0%b8%a8%e0%b8%a7%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95\/","title":{"rendered":"\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e30\u0e41\u0e19\u0e19\u0e2a\u0e2d\u0e1a\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 Digital Skill Training 2022 \u0e2b\u0e31\u0e27\u0e02\u0e49\u0e2d Excel Advanced"},"content":{"rendered":"<p>\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 (Digital Skill Training 2022) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e04\u0e27\u0e32\u0e21\u0e09\u0e25\u0e32\u0e14\u0e17\u0e32\u0e07\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2565 \u0e0b\u0e36\u0e48\u0e07 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e13\u0e31\u0e10\u0e18\u0e34\u0e14\u0e32 \u0e17\u0e36\u0e19\u0e23\u0e16 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e07\u0e32\u0e19\u0e41\u0e1c\u0e19\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e30\u0e41\u0e19\u0e19\u0e2a\u0e2d\u0e1a\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e43\u0e19\u0e2b\u0e31\u0e27\u0e02\u0e49\u0e2d Excel Advanced \u0e42\u0e14\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e41\u0e25\u0e30\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 Digital Transformation 2022 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 6 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2565 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e0a\u0e31\u0e49\u0e19 4 \u0e2d\u0e32\u0e04\u0e32\u0e23 50 \u0e1b\u0e35 \u0e27\u0e34\u0e28\u0e27\u0e30\u0e23\u0e27\u0e21\u0e43\u0e08 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<br \/>\n\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e02\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e21\u0e32 \u0e13 \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49<br \/>\n<img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-27071\" src=\"https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305546871_5587635961258920_9204313092506497783_n.jpg\" alt=\"\" width=\"2000\" height=\"1162\" srcset=\"https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305546871_5587635961258920_9204313092506497783_n.jpg 2000w, https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305546871_5587635961258920_9204313092506497783_n-1536x892.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><img decoding=\"async\" class=\"alignnone size-medium wp-image-27072\" src=\"https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305665131_5587635984592251_4159612492922837457_n.jpg\" alt=\"\" width=\"2000\" height=\"1500\" srcset=\"https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305665131_5587635984592251_4159612492922837457_n.jpg 2000w, https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305665131_5587635984592251_4159612492922837457_n-1536x1152.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 (Digital Skill Training 2022) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e04\u0e27\u0e32\u0e21\u0e09\u0e25\u0e32\u0e14\u0e17\u0e32\u0e07\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2565 \u0e0b\u0e36\u0e48\u0e07 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e13\u0e31\u0e10\u0e18\u0e34\u0e14\u0e32 \u0e17\u0e36\u0e19\u0e23\u0e16 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e07\u0e32\u0e19\u0e41\u0e1c\u0e19\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e30\u0e41\u0e19\u0e19\u0e2a\u0e2d\u0e1a\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e43\u0e19\u0e2b\u0e31\u0e27\u0e02\u0e49\u0e2d Excel Advanced \u0e42\u0e14\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e41\u0e25\u0e30\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 Digital Transformation 2022 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 6 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2565 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e0a\u0e31\u0e49\u0e19 4 \u0e2d\u0e32\u0e04\u0e32\u0e23 50 \u0e1b\u0e35 \u0e27\u0e34\u0e28\u0e27\u0e30\u0e23\u0e27\u0e21\u0e43\u0e08 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e02\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e21\u0e32 \u0e13 \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49<\/p>\n","protected":false},"author":8,"featured_media":27070,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1"],"rttpg_featured_image_url":{"full":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",2000,1500,false],"landscape":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",2000,1500,false],"portraits":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",2000,1500,false],"thumbnail":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",128,96,false],"medium":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",2000,1500,false],"large":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",2000,1500,false],"1536x1536":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n-1536x1152.jpg",1536,1152,true],"2048x2048":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",2000,1500,false],"tp-image-grid":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",700,525,false],"unipix-blog":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",560,420,false],"unipix-blog-2":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",160,120,false],"unipix-blog-3":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",280,210,false],"unipix-professor":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",300,225,false],"unipix-portfolio":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",347,260,false],"unipix-portfolio-2":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",387,290,false],"unipix-program":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",300,225,false],"unipix-research":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",410,308,false],"unipix-footer-blog":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/09\/305625712_5587636144592235_8047623405294631871_n.jpg",80,60,false]},"rttpg_author":{"display_name":"\u0e1d\u0e48\u0e32\u0e22\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23","author_link":"https:\/\/www.en.kku.ac.th\/web\/author\/webenpr\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.en.kku.ac.th\/web\/category\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%93%e0%b8%b0\/\" rel=\"category tag\">\u0e02\u0e48\u0e32\u0e27\u0e04\u0e13\u0e30<\/a>","rttpg_excerpt":"\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 (Digital Skill Training 2022) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e04\u0e27\u0e32\u0e21\u0e09\u0e25\u0e32\u0e14\u0e17\u0e32\u0e07\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2565 \u0e0b\u0e36\u0e48\u0e07 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e13\u0e31\u0e10\u0e18\u0e34\u0e14\u0e32 \u0e17\u0e36\u0e19\u0e23\u0e16 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e07\u0e32\u0e19\u0e41\u0e1c\u0e19\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e30\u0e41\u0e19\u0e19\u0e2a\u0e2d\u0e1a\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e43\u0e19\u0e2b\u0e31\u0e27\u0e02\u0e49\u0e2d Excel Advanced \u0e42\u0e14\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e41\u0e25\u0e30\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 Digital Transformation 2022 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 6 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2565 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e0a\u0e31\u0e49\u0e19 4 \u0e2d\u0e32\u0e04\u0e32\u0e23 50 \u0e1b\u0e35 \u0e27\u0e34\u0e28\u0e27\u0e30\u0e23\u0e27\u0e21\u0e43\u0e08 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e02\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e21\u0e32 \u0e13 \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49","_links":{"self":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/27069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/comments?post=27069"}],"version-history":[{"count":2,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/27069\/revisions"}],"predecessor-version":[{"id":27074,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/27069\/revisions\/27074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/media\/27070"}],"wp:attachment":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/media?parent=27069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/categories?post=27069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/tags?post=27069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}