{"id":27263,"date":"2022-11-04T11:56:52","date_gmt":"2022-11-04T04:56:52","guid":{"rendered":"https:\/\/www.en.kku.ac.th\/web\/?p=27263"},"modified":"2022-11-04T11:56:52","modified_gmt":"2022-11-04T04:56:52","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b2%e0%b8%aa%e0%b8%b1%e0%b8%a1%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a5-8","status":"publish","type":"post","link":"https:\/\/www.en.kku.ac.th\/web\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b2%e0%b8%aa%e0%b8%b1%e0%b8%a1%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a5-8\/","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2564\/2565 Intercultural and Global OITA Based Education (IGLOBE) for Spring and Fall entries 2023-2024"},"content":{"rendered":"<p>\u0e14\u0e49\u0e27\u0e22 Oita University \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565\/2566 Intercultural and Global OITA Based Education (IGLOBE) for Spring and Fall entries 2023-2024 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 1 \u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2b\u0e23\u0e37\u0e2d 1 \u0e1b\u0e35<\/p>\n<p><strong>\u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19 \u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49<\/strong><\/p>\n<ol>\n<li>1. \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e15\u0e47\u0e21\u0e40\u0e27\u0e25\u0e32\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e2b\u0e23\u0e37\u0e2d \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e01\u0e15\u0e34 \u0e13 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e15\u0e49\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14<\/li>\n<li>\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e30\u0e41\u0e19\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a TOEFL 500 \u0e2b\u0e23\u0e37\u0e2d IELTS 6.0 \u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e04\u0e30\u0e41\u0e19\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e29\u0e32\u0e1e\u0e39\u0e14 (Native Speaker) \u0e2b\u0e23\u0e37\u0e2d \u0e21\u0e35\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e27\u0e31\u0e14\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 (Japanese Language Proficiency Test: JLPT) \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e2a\u0e2d\u0e1a JPLT \u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19<\/li>\n<li>\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e13 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e15\u0e49\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14<\/li>\n<li>\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e14\u0e49<\/li>\n<li>\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e01\u0e23\u0e30\u0e15\u0e37\u0e19\u0e23\u0e37\u0e2d\u0e23\u0e49\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 IGLOBE<\/li>\n<li>6. \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e13 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e15\u0e49\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e31\u0e01\u0e08\u0e32\u0e01\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e34\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e13 Oita University<\/li>\n<li>\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u201cCollege Student Visa\u201d \u0e15\u0e32\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 Japanese Immigration<\/li>\n<\/ol>\n<p><strong>\u00a0\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23 \u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19 2 \u0e0a\u0e48\u0e27\u0e07 \u0e04\u0e37\u0e2d<\/strong><\/p>\n<ol>\n<li><u>April 2023 (Spring Semester) <\/u>\u0e01\u0e23\u0e38\u0e13\u0e32\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e43\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14<\/li>\n<\/ol>\n<p><strong>\u0e20\u0e32\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 15 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2565<\/strong><\/p>\n<ol start=\"2\">\n<li><u>October 2023 (Fall Semester) <\/u>\u0e01\u0e23\u0e38\u0e13\u0e32\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e43\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14<\/li>\n<\/ol>\n<p><strong>\u0e20\u0e32\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 8 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2566<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08\u0e42\u0e1b\u0e23\u0e14\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e43\u0e2b\u0e49\u0e23\u0e2d\u0e1a\u0e04\u0e2d\u0e1a\u0e01\u0e48\u0e2d\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48<\/p>\n<p><a href=\"https:\/\/drive.google.com\/drive\/folders\/1_uCsQDI1ldxulNCYTr8yDH3WetzBjzcf\">https:\/\/drive.google.com\/drive\/folders\/1_uCsQDI1ldxulNCYTr8yDH3WetzBjzcf<\/a><\/p>\n<p>\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e2a\u0e48\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e27\u0e34\u0e40\u0e17\u0e28\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e0a\u0e31\u0e49\u0e19 7 \u0e15\u0e36\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e27\u0e34\u0e08\u0e34\u0e15\u0e23 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e14\u0e49\u0e27\u0e22 Oita University \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565\/2566 Intercultural and Global OITA Based Education (IGLOBE) for Spring and Fall entries 2023-2024 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 1 \u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2b\u0e23\u0e37\u0e2d 1 \u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19 \u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49 1. \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e15\u0e47\u0e21\u0e40\u0e27\u0e25\u0e32\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e2b\u0e23\u0e37\u0e2d \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e01\u0e15\u0e34 \u0e13 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e15\u0e49\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14 \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e30\u0e41\u0e19\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a TOEFL 500 \u0e2b\u0e23\u0e37\u0e2d IELTS 6.0 \u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e04\u0e30\u0e41\u0e19\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e29\u0e32\u0e1e\u0e39\u0e14 (Native Speaker) \u0e2b\u0e23\u0e37\u0e2d \u0e21\u0e35\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e27\u0e31\u0e14\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 (Japanese Language Proficiency Test: JLPT) \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e2a\u0e2d\u0e1a JPLT&#8230;<\/p>\n","protected":false},"author":8,"featured_media":27264,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1"],"rttpg_featured_image_url":{"full":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",1400,590,false],"landscape":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",1400,590,false],"portraits":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",1400,590,false],"thumbnail":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",128,54,false],"medium":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",1400,590,false],"large":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",1400,590,false],"1536x1536":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",1400,590,false],"2048x2048":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",1400,590,false],"tp-image-grid":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",700,295,false],"unipix-blog":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",615,259,false],"unipix-blog-2":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",190,80,false],"unipix-blog-3":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",280,118,false],"unipix-professor":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",300,126,false],"unipix-portfolio":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",360,152,false],"unipix-portfolio-2":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",400,169,false],"unipix-program":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",300,126,false],"unipix-research":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",410,173,false],"unipix-footer-blog":["https:\/\/www.en.kku.ac.th\/web\/wp-content\/uploads\/2022\/11\/309641437_2102286273289036_2561261654761254165_n.jpg",80,34,false]},"rttpg_author":{"display_name":"\u0e1d\u0e48\u0e32\u0e22\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23","author_link":"https:\/\/www.en.kku.ac.th\/web\/author\/webenpr\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.en.kku.ac.th\/web\/category\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%93%e0%b8%b0\/\" rel=\"category tag\">\u0e02\u0e48\u0e32\u0e27\u0e04\u0e13\u0e30<\/a>","rttpg_excerpt":"\u0e14\u0e49\u0e27\u0e22 Oita University \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565\/2566 Intercultural and Global OITA Based Education (IGLOBE) for Spring and Fall entries 2023-2024 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 1 \u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2b\u0e23\u0e37\u0e2d 1 \u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19 \u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49 1. \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e15\u0e47\u0e21\u0e40\u0e27\u0e25\u0e32\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e2b\u0e23\u0e37\u0e2d \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e01\u0e15\u0e34 \u0e13 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e15\u0e49\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14 \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e30\u0e41\u0e19\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a TOEFL 500 \u0e2b\u0e23\u0e37\u0e2d IELTS 6.0 \u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e04\u0e30\u0e41\u0e19\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e29\u0e32\u0e1e\u0e39\u0e14 (Native Speaker) \u0e2b\u0e23\u0e37\u0e2d \u0e21\u0e35\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e27\u0e31\u0e14\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 (Japanese Language Proficiency Test: JLPT) \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e2a\u0e2d\u0e1a JPLT...","_links":{"self":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/27263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/comments?post=27263"}],"version-history":[{"count":1,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/27263\/revisions"}],"predecessor-version":[{"id":27265,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/posts\/27263\/revisions\/27265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/media\/27264"}],"wp:attachment":[{"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/media?parent=27263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/categories?post=27263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.en.kku.ac.th\/web\/wp-json\/wp\/v2\/tags?post=27263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}